{"id":14116,"date":"2019-03-22T13:00:23","date_gmt":"2019-03-22T13:00:23","guid":{"rendered":"https:\/\/*.stellenanzeigen.de?page_id=14116"},"modified":"2019-07-22T10:41:31","modified_gmt":"2019-07-22T10:41:31","slug":"arbeitsmarkt","status":"publish","type":"page","link":"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/","title":{"rendered":"Arbeitsmarkt"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":103,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blocks.php","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-14116","page","type-page","status-publish","hentry","entry","post-no-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbeitsmarkt | careeasy - Dein Karrieremagazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbeitsmarkt | careeasy - Dein Karrieremagazin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/\" \/>\n<meta property=\"og:site_name\" content=\"careeasy - Dein Karrieremagazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/stellenanzeigen.de\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-22T10:41:31+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/arbeitsmarkt\\\/\",\"url\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/arbeitsmarkt\\\/\",\"name\":\"Arbeitsmarkt | careeasy - Dein Karrieremagazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/#website\"},\"datePublished\":\"2019-03-22T13:00:23+00:00\",\"dateModified\":\"2019-07-22T10:41:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/arbeitsmarkt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/arbeitsmarkt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/arbeitsmarkt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Careeasy\",\"item\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arbeitsmarkt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/#website\",\"url\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/\",\"name\":\"careeasy - Dein Karrieremagazin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/#organization\",\"name\":\"careeasy - Dein Karrieremagazin\",\"url\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/careeasy_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/careeasy_logo.jpg\",\"width\":701,\"height\":223,\"caption\":\"careeasy - Dein Karrieremagazin\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stellenanzeigen.de\\\/careeasy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/stellenanzeigen.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arbeitsmarkt | careeasy - Dein Karrieremagazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/","og_locale":"de_DE","og_type":"article","og_title":"Arbeitsmarkt | careeasy - Dein Karrieremagazin","og_url":"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/","og_site_name":"careeasy - Dein Karrieremagazin","article_publisher":"https:\/\/www.facebook.com\/stellenanzeigen.de\/","article_modified_time":"2019-07-22T10:41:31+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/","url":"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/","name":"Arbeitsmarkt | careeasy - Dein Karrieremagazin","isPartOf":{"@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/#website"},"datePublished":"2019-03-22T13:00:23+00:00","dateModified":"2019-07-22T10:41:31+00:00","breadcrumb":{"@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/arbeitsmarkt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Careeasy","item":"https:\/\/www.stellenanzeigen.de\/careeasy\/"},{"@type":"ListItem","position":2,"name":"Arbeitsmarkt"}]},{"@type":"WebSite","@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/#website","url":"https:\/\/www.stellenanzeigen.de\/careeasy\/","name":"careeasy - Dein Karrieremagazin","description":"","publisher":{"@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stellenanzeigen.de\/careeasy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/#organization","name":"careeasy - Dein Karrieremagazin","url":"https:\/\/www.stellenanzeigen.de\/careeasy\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/#\/schema\/logo\/image\/","url":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-content\/uploads\/2024\/03\/careeasy_logo.jpg","contentUrl":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-content\/uploads\/2024\/03\/careeasy_logo.jpg","width":701,"height":223,"caption":"careeasy - Dein Karrieremagazin"},"image":{"@id":"https:\/\/www.stellenanzeigen.de\/careeasy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/stellenanzeigen.de\/"]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"neomag-medium":false,"neomag-big":false,"neomag-large":false,"neomag-huge":false},"uagb_author_info":{"display_name":"stellenanzeigen.de","author_link":"https:\/\/www.stellenanzeigen.de\/careeasy\/author\/stellenanzeigen-de\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/pages\/14116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/comments?post=14116"}],"version-history":[{"count":2,"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/pages\/14116\/revisions"}],"predecessor-version":[{"id":14861,"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/pages\/14116\/revisions\/14861"}],"wp:attachment":[{"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/media?parent=14116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/categories?post=14116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stellenanzeigen.de\/careeasy\/wp-json\/wp\/v2\/tags?post=14116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}